{"id":13312317,"date":"2025-11-24T14:09:28","date_gmt":"2025-11-24T17:09:28","guid":{"rendered":"https:\/\/alvexltda.cl\/globo\/producto\/anti-stress-cube\/"},"modified":"2026-02-25T10:46:00","modified_gmt":"2026-02-25T13:46:00","slug":"anti-stress-cube","status":"publish","type":"product","link":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/","title":{"rendered":"Anti Stress Cube"},"content":{"rendered":"<p>Cubo antiestr\u00e9s de PU en acabado suave. Confeccionado en poliuretano (PU), material flexible y resistente.<br \/>\nCuenta con dise\u00f1o ergon\u00f3mico en forma de dado, disponible en colores blanco y negro, pensado para ofrecer comodidad en cada uso.<br \/>\nEs ideal para aliviar la tensi\u00f3n en momentos de estr\u00e9s, regalar en campa\u00f1as corporativas o utilizar como accesorio promocional divertido y funcional.<\/p>\n<p>TAHG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cubo antiestr\u00e9s de PU en acabado suave. Confeccionado en poliuretano (PU), material flexible y resistente. Cuenta con dise\u00f1o ergon\u00f3mico en<\/p>\n","protected":false},"featured_media":13312318,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[719],"product_tag":[],"class_list":{"0":"post-13312317","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-nombre","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anti Stress Cube - Globo Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anti Stress Cube\" \/>\n<meta property=\"og:description\" content=\"Cubo antiestr\u00e9s de PU en acabado suave. Confeccionado en poliuretano (PU), material flexible y resistente. Cuenta con dise\u00f1o ergon\u00f3mico en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/\" \/>\n<meta property=\"og:site_name\" content=\"Globo Marketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T13:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2025\/11\/RWLRN9PRo8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/\",\"name\":\"Anti Stress Cube - Globo Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/RWLRN9PRo8.jpg\",\"datePublished\":\"2025-11-24T17:09:28+00:00\",\"dateModified\":\"2026-02-25T13:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/RWLRN9PRo8.jpg\",\"contentUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/RWLRN9PRo8.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-nombre\\\/anti-stress-cube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anti Stress Cube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#website\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\",\"name\":\"Globo Marketing\",\"description\":\"Regalos Corporativos Personalizados en Chile\",\"publisher\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#organization\"},\"alternateName\":\"GloboMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#organization\",\"name\":\"Globo Marketing Limitada\",\"alternateName\":\"Globo Marketing\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_low.png\",\"contentUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_low.png\",\"width\":1,\"height\":1,\"caption\":\"Globo Marketing Limitada\"},\"image\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Globo-Marketing-133480783339169\\\/\",\"https:\\\/\\\/www.instagram.com\\\/globo.marketingcl\\\/\"],\"description\":\"En GloboMarketing ofrecemos regalos corporativos personalizados con env\u00edo a todo Chile, fortaleciendo las relaciones comerciales y potenciando la imagen de marca de nuestros clientes.\",\"email\":\"contacto@globomarketing.cl\",\"telephone\":\"+56228840500\",\"legalName\":\"Comercializadora Globomarketing Limitada\",\"foundingDate\":\"2013-03-01\",\"vatID\":\"76114439-1\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anti Stress Cube - Globo Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/","og_locale":"es_ES","og_type":"article","og_title":"Anti Stress Cube","og_description":"Cubo antiestr\u00e9s de PU en acabado suave. Confeccionado en poliuretano (PU), material flexible y resistente. Cuenta con dise\u00f1o ergon\u00f3mico en","og_url":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/","og_site_name":"Globo Marketing","article_publisher":"https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/","article_modified_time":"2026-02-25T13:46:00+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2025\/11\/RWLRN9PRo8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/","url":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/","name":"Anti Stress Cube - Globo Marketing","isPartOf":{"@id":"https:\/\/alvexltda.cl\/globo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/#primaryimage"},"image":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/#primaryimage"},"thumbnailUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2025\/11\/RWLRN9PRo8.jpg","datePublished":"2025-11-24T17:09:28+00:00","dateModified":"2026-02-25T13:46:00+00:00","breadcrumb":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/#primaryimage","url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2025\/11\/RWLRN9PRo8.jpg","contentUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2025\/11\/RWLRN9PRo8.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/alvexltda.cl\/globo\/sin-nombre\/anti-stress-cube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alvexltda.cl\/globo\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/alvexltda.cl\/globo\/store\/"},{"@type":"ListItem","position":3,"name":"Anti Stress Cube"}]},{"@type":"WebSite","@id":"https:\/\/alvexltda.cl\/globo\/#website","url":"https:\/\/alvexltda.cl\/globo\/","name":"Globo Marketing","description":"Regalos Corporativos Personalizados en Chile","publisher":{"@id":"https:\/\/alvexltda.cl\/globo\/#organization"},"alternateName":"GloboMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alvexltda.cl\/globo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/alvexltda.cl\/globo\/#organization","name":"Globo Marketing Limitada","alternateName":"Globo Marketing","url":"https:\/\/alvexltda.cl\/globo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/alvexltda.cl\/globo\/#\/schema\/logo\/image\/","url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2016\/10\/logo_low.png","contentUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2016\/10\/logo_low.png","width":1,"height":1,"caption":"Globo Marketing Limitada"},"image":{"@id":"https:\/\/alvexltda.cl\/globo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/","https:\/\/www.instagram.com\/globo.marketingcl\/"],"description":"En GloboMarketing ofrecemos regalos corporativos personalizados con env\u00edo a todo Chile, fortaleciendo las relaciones comerciales y potenciando la imagen de marca de nuestros clientes.","email":"contacto@globomarketing.cl","telephone":"+56228840500","legalName":"Comercializadora Globomarketing Limitada","foundingDate":"2013-03-01","vatID":"76114439-1","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/alvexltda.cl\/globo\/"}]}},"_links":{"self":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product\/13312317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/comments?post=13312317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/media\/13312318"}],"wp:attachment":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/media?parent=13312317"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_brand?post=13312317"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_cat?post=13312317"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_tag?post=13312317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}