{"id":2455,"date":"2023-01-09T22:27:41","date_gmt":"2023-01-10T01:27:41","guid":{"rendered":"https:\/\/alvexltda.cl\/globo\/?post_type=product&#038;p=2455"},"modified":"2026-01-30T16:17:03","modified_gmt":"2026-01-30T19:17:03","slug":"cuaderno-eco-colors","status":"publish","type":"product","link":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/","title":{"rendered":"Cuaderno Eco Colors"},"content":{"rendered":"<p>Cuaderno anillado colors tama\u00f1o A6 con50 hojas rayadas. Realizado con tapa dura elaborada en cart\u00f3n reciclado. Incluye bol\u00edgrafo con pulsador. Medidas: 8 x 12 cm. ReUseMe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuaderno anillado colors tama\u00f1o A6 con50 hojas rayadas. Realizado con tapa dura elaborada en cart\u00f3n reciclado. Incluye bol\u00edgrafo con pulsador.<\/p>\n","protected":false},"featured_media":13292441,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"product_tag":[385,390,388],"class_list":{"0":"post-2455","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categoria","7":"product_tag-back-to-school","8":"product_tag-cuaderno","9":"product_tag-ecologico","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cuaderno Eco Colors - Globo Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuaderno Eco Colors\" \/>\n<meta property=\"og:description\" content=\"Cuaderno anillado colors tama\u00f1o A6 con50 hojas rayadas. Realizado con tapa dura elaborada en cart\u00f3n reciclado. Incluye bol\u00edgrafo con pulsador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/\" \/>\n<meta property=\"og:site_name\" content=\"Globo Marketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T19:17:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2023\/01\/Cuaderno-Eco-Colors.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/\",\"name\":\"Cuaderno Eco Colors - Globo Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cuaderno-Eco-Colors.jpg\",\"datePublished\":\"2023-01-10T01:27:41+00:00\",\"dateModified\":\"2026-01-30T19:17:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cuaderno-Eco-Colors.jpg\",\"contentUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cuaderno-Eco-Colors.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/sin-categoria\\\/cuaderno-eco-colors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuaderno Eco Colors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#website\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\",\"name\":\"Globo Marketing\",\"description\":\"Regalos Corporativos Personalizados en Chile\",\"publisher\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#organization\"},\"alternateName\":\"GloboMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#organization\",\"name\":\"Globo Marketing Limitada\",\"alternateName\":\"Globo Marketing\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_low.png\",\"contentUrl\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_low.png\",\"width\":1,\"height\":1,\"caption\":\"Globo Marketing Limitada\"},\"image\":{\"@id\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Globo-Marketing-133480783339169\\\/\",\"https:\\\/\\\/www.instagram.com\\\/globo.marketingcl\\\/\"],\"description\":\"En GloboMarketing ofrecemos regalos corporativos personalizados con env\u00edo a todo Chile, fortaleciendo las relaciones comerciales y potenciando la imagen de marca de nuestros clientes.\",\"email\":\"contacto@globomarketing.cl\",\"telephone\":\"+56228840500\",\"legalName\":\"Comercializadora Globomarketing Limitada\",\"foundingDate\":\"2013-03-01\",\"vatID\":\"76114439-1\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/alvexltda.cl\\\/globo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cuaderno Eco Colors - Globo Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/","og_locale":"es_ES","og_type":"article","og_title":"Cuaderno Eco Colors","og_description":"Cuaderno anillado colors tama\u00f1o A6 con50 hojas rayadas. Realizado con tapa dura elaborada en cart\u00f3n reciclado. Incluye bol\u00edgrafo con pulsador.","og_url":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/","og_site_name":"Globo Marketing","article_publisher":"https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/","article_modified_time":"2026-01-30T19:17:03+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2023\/01\/Cuaderno-Eco-Colors.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/","url":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/","name":"Cuaderno Eco Colors - Globo Marketing","isPartOf":{"@id":"https:\/\/alvexltda.cl\/globo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/#primaryimage"},"image":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/#primaryimage"},"thumbnailUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2023\/01\/Cuaderno-Eco-Colors.jpg","datePublished":"2023-01-10T01:27:41+00:00","dateModified":"2026-01-30T19:17:03+00:00","breadcrumb":{"@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/#primaryimage","url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2023\/01\/Cuaderno-Eco-Colors.jpg","contentUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2023\/01\/Cuaderno-Eco-Colors.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/alvexltda.cl\/globo\/sin-categoria\/cuaderno-eco-colors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alvexltda.cl\/globo\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/alvexltda.cl\/globo\/store\/"},{"@type":"ListItem","position":3,"name":"Cuaderno Eco Colors"}]},{"@type":"WebSite","@id":"https:\/\/alvexltda.cl\/globo\/#website","url":"https:\/\/alvexltda.cl\/globo\/","name":"Globo Marketing","description":"Regalos Corporativos Personalizados en Chile","publisher":{"@id":"https:\/\/alvexltda.cl\/globo\/#organization"},"alternateName":"GloboMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alvexltda.cl\/globo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/alvexltda.cl\/globo\/#organization","name":"Globo Marketing Limitada","alternateName":"Globo Marketing","url":"https:\/\/alvexltda.cl\/globo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/alvexltda.cl\/globo\/#\/schema\/logo\/image\/","url":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2016\/10\/logo_low.png","contentUrl":"https:\/\/alvexltda.cl\/globo\/wp-content\/uploads\/2016\/10\/logo_low.png","width":1,"height":1,"caption":"Globo Marketing Limitada"},"image":{"@id":"https:\/\/alvexltda.cl\/globo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Globo-Marketing-133480783339169\/","https:\/\/www.instagram.com\/globo.marketingcl\/"],"description":"En GloboMarketing ofrecemos regalos corporativos personalizados con env\u00edo a todo Chile, fortaleciendo las relaciones comerciales y potenciando la imagen de marca de nuestros clientes.","email":"contacto@globomarketing.cl","telephone":"+56228840500","legalName":"Comercializadora Globomarketing Limitada","foundingDate":"2013-03-01","vatID":"76114439-1","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/alvexltda.cl\/globo\/"}]}},"_links":{"self":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product\/2455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/comments?post=2455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/media\/13292441"}],"wp:attachment":[{"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/media?parent=2455"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_brand?post=2455"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_cat?post=2455"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/alvexltda.cl\/globo\/wp-json\/wp\/v2\/product_tag?post=2455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}